{"id":137,"count":3,"description":"","link":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/","name":"gafas esqu\u00ed","slug":"gafas-esqui","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>gafas esqu\u00ed - Esquiades Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gafas esqu\u00ed - Esquiades Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/\" \/>\n<meta property=\"og:site_name\" content=\"Esquiades Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/\",\"url\":\"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/\",\"name\":\"gafas esqu\u00ed - Esquiades Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.esquiades.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.esquiades.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gafas esqu\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.esquiades.com\/blog\/#website\",\"url\":\"https:\/\/www.esquiades.com\/blog\/\",\"name\":\"Esquiades Blog\",\"description\":\"Pasi\u00f3n por la nieve y la monta\u00f1a\",\"publisher\":{\"@id\":\"https:\/\/www.esquiades.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.esquiades.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.esquiades.com\/blog\/#organization\",\"name\":\"Esquiades Blog\",\"url\":\"https:\/\/www.esquiades.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.esquiades.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.esquiades.com\/blog\/app\/uploads\/2017\/02\/esquiades-LOGO-2.jpg\",\"contentUrl\":\"https:\/\/www.esquiades.com\/blog\/app\/uploads\/2017\/02\/esquiades-LOGO-2.jpg\",\"width\":397,\"height\":157,\"caption\":\"Esquiades Blog\"},\"image\":{\"@id\":\"https:\/\/www.esquiades.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"gafas esqu\u00ed - Esquiades Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/","og_locale":"es_ES","og_type":"article","og_title":"gafas esqu\u00ed - Esquiades Blog","og_url":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/","og_site_name":"Esquiades Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/","url":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/","name":"gafas esqu\u00ed - Esquiades Blog","isPartOf":{"@id":"https:\/\/www.esquiades.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.esquiades.com\/blog\/tag\/gafas-esqui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.esquiades.com\/blog\/"},{"@type":"ListItem","position":2,"name":"gafas esqu\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/www.esquiades.com\/blog\/#website","url":"https:\/\/www.esquiades.com\/blog\/","name":"Esquiades Blog","description":"Pasi\u00f3n por la nieve y la monta\u00f1a","publisher":{"@id":"https:\/\/www.esquiades.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esquiades.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.esquiades.com\/blog\/#organization","name":"Esquiades Blog","url":"https:\/\/www.esquiades.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.esquiades.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.esquiades.com\/blog\/app\/uploads\/2017\/02\/esquiades-LOGO-2.jpg","contentUrl":"https:\/\/www.esquiades.com\/blog\/app\/uploads\/2017\/02\/esquiades-LOGO-2.jpg","width":397,"height":157,"caption":"Esquiades Blog"},"image":{"@id":"https:\/\/www.esquiades.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.esquiades.com\/blog\/wp-json\/wp\/v2\/tags\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esquiades.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.esquiades.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.esquiades.com\/blog\/wp-json\/wp\/v2\/posts?tags=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}